{"id":565,"date":"2025-02-20T07:56:29","date_gmt":"2025-02-20T07:56:29","guid":{"rendered":"https:\/\/saules-gojus-mokykla.w-i.lt\/?page_id=565"},"modified":"2025-03-24T12:04:16","modified_gmt":"2025-03-24T12:04:16","slug":"enrollment","status":"publish","type":"page","link":"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/","title":{"rendered":"Enrolment"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-565","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Enrolment to private school in Vilnius | Saules gojus<\/title>\n<meta name=\"description\" content=\"Enrolment to private school in Vilnius \u2705 Bilingual \u2705 Learn about the admissions process, requirements and deadlines \u261b Join our community!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enrolment to private school in Vilnius | Saules gojus\" \/>\n<meta property=\"og:description\" content=\"Enrolment to private school in Vilnius \u2705 Bilingual \u2705 Learn about the admissions process, requirements and deadlines \u261b Join our community!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/\" \/>\n<meta property=\"og:site_name\" content=\"Saules gojus\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T12:04:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/\",\"url\":\"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/\",\"name\":\"Enrolment to private school in Vilnius | Saules gojus\",\"isPartOf\":{\"@id\":\"https:\/\/mokykla.saulesgojus.lt\/en\/#website\"},\"datePublished\":\"2025-02-20T07:56:29+00:00\",\"dateModified\":\"2025-03-24T12:04:16+00:00\",\"description\":\"Enrolment to private school in Vilnius \u2705 Bilingual \u2705 Learn about the admissions process, requirements and deadlines \u261b Join our community!\",\"breadcrumb\":{\"@id\":\"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/mokykla.saulesgojus.lt\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enrolment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mokykla.saulesgojus.lt\/en\/#website\",\"url\":\"https:\/\/mokykla.saulesgojus.lt\/en\/\",\"name\":\"Saul\u0117s Gojus\",\"description\":\"\",\"alternateName\":\"Saul\u0117s Gojus\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/mokykla.saulesgojus.lt\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enrolment to private school in Vilnius | Saules gojus","description":"Enrolment to private school in Vilnius \u2705 Bilingual \u2705 Learn about the admissions process, requirements and deadlines \u261b Join our community!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/","og_locale":"en_US","og_type":"article","og_title":"Enrolment to private school in Vilnius | Saules gojus","og_description":"Enrolment to private school in Vilnius \u2705 Bilingual \u2705 Learn about the admissions process, requirements and deadlines \u261b Join our community!","og_url":"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/","og_site_name":"Saules gojus","article_modified_time":"2025-03-24T12:04:16+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/","url":"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/","name":"Enrolment to private school in Vilnius | Saules gojus","isPartOf":{"@id":"https:\/\/mokykla.saulesgojus.lt\/en\/#website"},"datePublished":"2025-02-20T07:56:29+00:00","dateModified":"2025-03-24T12:04:16+00:00","description":"Enrolment to private school in Vilnius \u2705 Bilingual \u2705 Learn about the admissions process, requirements and deadlines \u261b Join our community!","breadcrumb":{"@id":"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mokykla.saulesgojus.lt\/en\/enrollment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mokykla.saulesgojus.lt\/en\/"},{"@type":"ListItem","position":2,"name":"Enrolment"}]},{"@type":"WebSite","@id":"https:\/\/mokykla.saulesgojus.lt\/en\/#website","url":"https:\/\/mokykla.saulesgojus.lt\/en\/","name":"Saul\u0117s Gojus","description":"","alternateName":"Saul\u0117s Gojus","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mokykla.saulesgojus.lt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/mokykla.saulesgojus.lt\/en\/wp-json\/wp\/v2\/pages\/565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mokykla.saulesgojus.lt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mokykla.saulesgojus.lt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mokykla.saulesgojus.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mokykla.saulesgojus.lt\/en\/wp-json\/wp\/v2\/comments?post=565"}],"version-history":[{"count":4,"href":"https:\/\/mokykla.saulesgojus.lt\/en\/wp-json\/wp\/v2\/pages\/565\/revisions"}],"predecessor-version":[{"id":758,"href":"https:\/\/mokykla.saulesgojus.lt\/en\/wp-json\/wp\/v2\/pages\/565\/revisions\/758"}],"wp:attachment":[{"href":"https:\/\/mokykla.saulesgojus.lt\/en\/wp-json\/wp\/v2\/media?parent=565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}